{"id":2938,"date":"2022-03-31T15:48:06","date_gmt":"2022-03-31T18:48:06","guid":{"rendered":"https:\/\/ecovision2025.ca\/?page_id=2938"},"modified":"2024-10-18T11:54:30","modified_gmt":"2024-10-18T14:54:30","slug":"pollinisateurs","status":"publish","type":"page","link":"https:\/\/ecovision2025.ca\/fr\/pollinisateurs\/","title":{"rendered":"pollinisateurs"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_header title=\u00a0\u00bbL&rsquo;importance des Pollinisateurs\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb title_tablet=\u00a0\u00bbL&rsquo;importance des Pollinisateurs\u00a0\u00bb title_phone=\u00a0\u00bbL&rsquo;importance des Pollinisateurs\u00a0\u00bb title_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_font_size=\u00a0\u00bb54px\u00a0\u00bb title_line_height=\u00a0\u00bb1.1em\u00a0\u00bb content_font_size=\u00a0\u00bb1px\u00a0\u00bb subhead_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb subhead_font_size=\u00a0\u00bb24px\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/04\/Pollinisateurs-bourdons-Web.jpg\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb min_height=\u00a0\u00bb543px\u00a0\u00bb custom_margin=\u00a0\u00bb||-154px|||\u00a0\u00bb custom_padding=\u00a0\u00bb95px||0px|||\u00a0\u00bb title_font_tablet=\u00a0\u00bb\u00a0\u00bb title_font_phone=\u00a0\u00bb\u00a0\u00bb title_font_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; min_height=\u00a0\u00bb3396px\u00a0\u00bb custom_margin=\u00a0\u00bb24px||0px|||\u00a0\u00bb custom_padding=\u00a0\u00bb2px|0px|0px|0px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Les pollinisateurs comme les abeilles et les papillons sont essentiels \u00e0 notre environnement et \u00e0 notre \u00e9conomie. Ils jouent un r\u00f4le important dans la croissance des arbres, des fleurs et des autres plantes partout dans le monde. En fait, pr\u00e8s de <a href=\"https:\/\/www.jardinsdefrance.org\/pollinisation-insectes-vertebres\/\" target=\"_blank\" rel=\"noopener\">85 %<\/a> de toutes les plantes \u00e0 fleurs en d\u00e9pendent pour produire des fruits et des graines. Selon <a href=\"https:\/\/pollinatorpartnership.ca\/fr\" target=\"_blank\" rel=\"noopener\">Pollinator Partnership<\/a>, les pollinisateurs sont \u00e9galement responsables d&rsquo;une bouch\u00e9e de nourriture sur trois que nous mangeons !<\/p>\n<p>Au-del\u00e0 de l&rsquo;agriculture, les pollinisateurs fournissent de nombreux autres avantages et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Service_%C3%A9cosyst%C3%A9mique\" target=\"_blank\" rel=\"noopener\">services \u00e9cosyst\u00e9miques<\/a> vitaux dans les environnements ruraux et urbains. Ils sont consid\u00e9r\u00e9s comme des esp\u00e8ces cl\u00e9s, car leurs activit\u00e9s permettent la croissance des arbres et d&rsquo;autres plantes, qui fournissent nourriture et abri aux animaux, grands et petits. De plus, ils jouent aussi un r\u00f4le dans la cha\u00eene alimentaire, car ils sont \u00e9galement des proies importantes pour d&rsquo;autres esp\u00e8ces, comme les oiseaux et les amphibiens.<\/p>\n<p>La protection des pollinisateurs est un enjeu important pour nos communaut\u00e9s. Nous avons besoin d&rsquo;eux pour pr\u00e9server les ressources alimentaires, la biodiversit\u00e9 des esp\u00e8ces v\u00e9g\u00e9tales et animales et le fonctionnement des \u00e9cosyst\u00e8mes. Autre fait important \u00e0 noter : en soutenant la v\u00e9g\u00e9tation, les pollinisateurs contribuent \u00e0 r\u00e9guler le climat et \u00e0 contr\u00f4ler l&rsquo;\u00e9rosion le long des cours d&rsquo;eau.<\/p>\n<p>Dans notre r\u00e9gion, les pollinisateurs indig\u00e8nes sont confront\u00e9s <a href=\"https:\/\/banwithaplan.org\/fr\/le-retablissement-des-pollinisateurs\/\" target=\"_blank\" rel=\"noopener\">aux m\u00eames menaces qu&rsquo;ailleurs<\/a>. Les scientifiques croient que la perte d&rsquo;habitats naturels pour se nourrir et nicher, les pesticides, l&rsquo;exposition \u00e0 la pollution, les parasites, les virus et les changements climatiques sont autant de raisons qui expliquent le d\u00e9clin continu de la diversit\u00e9 et de l&rsquo;abondance des pollinisateurs. Malgr\u00e9 tout, il existe des moyens d&rsquo;aider les pollinisateurs. Dans les prochaines sections, vous d\u00e9couvrirez comment.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_cta title=\u00a0\u00bbAidez les pollinisateurs en laissant pousser votre gazon ce printemps!\u00a0\u00bb button_text=\u00a0\u00bbClick Here\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb30px\u00a0\u00bb body_font_size=\u00a0\u00bb18px\u00a0\u00bb background_color=\u00a0\u00bb#0071BA\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>\u00ab <em>En mai on laisse pousser<\/em>\u00a0\u00bb a donn\u00e9 place \u00e0 un mouvement important en faveur des pollinisateurs. Ce printemps, en 2024, faisons place \u00e0 la campagne \u00ab\u00a0Ce gazon est tondu moins souvent, pour le bonheur des pollinisateurs!\u00a0\u00bb<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1063px\u00a0\u00bb custom_margin=\u00a0\u00bb34px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||33px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2024\/04\/Enseigne-Municipalites-En-Mai-2024_Annonce-Facebook.jpg\u00a0\u00bb title_text=\u00a0\u00bbEnseigne Municipalites &#8211; En Mai 2024_Annonce Facebook\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Il n\u2019est pas n\u00e9cessaire d\u2019attendre \u00e0 la fin mai pour tondre. En observant notre cour, on peut juger quelles actions sont les meilleures pour encourager les pollinisateurs chez nous, tout en \u00e9valuant la capacit\u00e9 de notre tondeuse! Par exemple, on peut tondre une fois \u00e0 la mi-mai ou la semaine d\u2019apr\u00e8s.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.6em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb min_height=\u00a0\u00bb401px\u00a0\u00bb custom_margin=\u00a0\u00bb0px|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|0px|0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>En 2022 et 2023, au mois de mai, les r\u00e9sidents \u00e9taient invit\u00e9s \u00e0 ne pas tondre leurs pelouses, ou du moins \u00e0 en laisser pousser une partie. Les nombreuses fleurs ont attir\u00e9 des abeilles, qui sortaient tout juste de terre.<\/p>\n<p>Ces insectes indig\u00e8nes comme les abeilles fouisseuses, qui ne piquent pratiquement pas, n\u2019attendent que le printemps pour trouver de la nourriture pendant leur tr\u00e8s court cycle de vie. Ce sont de tr\u00e8s importants pollinisateurs, toutes comme les reines bourdons qui \u00e9mergent aussi au printemps.<\/p>\n<p>Cette ann\u00e9e, nous pouvons encore faire notre part pour les aider en tondant moins souvent, tout en observant les pollinisateurs qui nous visitent.<\/p>\n<p>Laquelle des 200 esp\u00e8ces d\u2019abeilles retrouv\u00e9es dans les Maritimes trouve-t-on dans nos cours? Quelles fleurs visitent-ils? A-t-on m\u00eame quelques papillons?<\/p>\n<p>Ces questions nous permettent d\u2019en savoir plus sur la diversit\u00e9 des esp\u00e8ces qui nous entourent. Elles permettent aussi de nous \u00e9clairer sur la fa\u00e7on de g\u00e9rer nos cours.<\/p>\n<p>Prendre note de ce qu\u2019on attire et de ce qui pousse permet de d\u00e9cider quand le temps est venu de tondre. Par exemple, on peut observer des facteurs comme la maturation des fleurs, pour pr\u00e9venir l\u2019aspect n\u00e9glig\u00e9 des pissenlits dont les graines s\u2019envolent. On peut donc tondre avant que ces fleurs ne se r\u00e9pandent partout.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_accordion _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_accordion_item title=\u00a0\u00bbPourquoi le slogan de la campagne pour aider les pollinisateurs en mai a-t-il chang\u00e9 cette ann\u00e9e?\u00a0\u00bb open=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li>En indiquant de ne pas tondre pendant tout le mois de mai, le slogan \u00ab\u00a0No Mow May\u00a0\u00bb (En mai on laisse pousser) \u00e9tait un peu trop restrictif pour ceux et celles qui voulaient participer, mais qui n&rsquo;\u00e9taient pas pr\u00eats \u00e0 s&rsquo;engager pleinement.<\/li>\n<li>L\u2019important est de demeurer flexible en laissant \u00e0 la population le choix de couper ou non avant la fin du mois de mai.<\/li>\n<li>Comme le d\u00e9but de nos printemps est de plus en plus chaud, l&rsquo;herbe commence parfois \u00e0 pousser d\u00e8s le mois d&rsquo;avril. \u00c0 la fin du mois de mai, elle peut \u00eatre assez longue, ce qui constitue un d\u00e9fi pour ceux qui ne disposent pas d&rsquo;une tondeuse \u00e0 gazon puissante.<\/li>\n<li>Une <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0006320717306201?via%3Dihub\" target=\"_blank\" rel=\"noopener\">\u00e9tude<\/a> montre que couper le gazon toutes les deux ou trois semaines peut aussi \u00eatre b\u00e9n\u00e9fique pour les pollinisateurs. L&rsquo;important est de trouver un \u00e9quilibre entre les besoins des pollinisateurs et ceux des citoyens en ce qui concerne la hauteur du gazon.<\/li>\n<li>\u00c0 noter qu\u2019au niveau de la municipalit\u00e9 de Shediac, <a href=\"https:\/\/shediac.ca\/~shediac\/images\/ByLawArrete59TallgrassesintheTownofShediac2019FINAL.pdf\" target=\"_blank\" rel=\"noopener\">l\u2019arr\u00eat\u00e9 sur les herbes hautes<\/a> est suspendu en mai, afin de suivre la tendance du mouvement qui a aussi lieu dans d\u2019autres r\u00e9gions.<\/li>\n<\/ul>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<h3>Des enseignes dans les zones moins tondues<\/h3>\n<p>Les municipalit\u00e9s de Shediac et Cap-Acadie installeront durant le mois de mai, des enseignes dans les zones moins tondues \u00e0 des emplacements choisis sur leurs terrains.<\/p>\n<p>Affichant le slogan \u00ab Ce gazon est tondu moins souvent, pour le bonheur des pollinisateurs \u00bb, ces enseignes nous montrent qu\u2019on peut continuer \u00e0 faire notre part pour aider ces insectes b\u00e9n\u00e9fiques.<\/p>\n<p>* \u00c0 noter que dans le cadre de cette initiative, la ville de Shediac a aussi suspendu <a href=\"https:\/\/shediac.ca\/images\/ByLawArrete59TallgrassesintheTownofShediac2019FINAL.pdf\" target=\"_blank\" rel=\"noopener\">l\u2019arr\u00eat\u00e9 des herbes hautes<\/a> pour le mois de mai.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_gallery gallery_ids=\u00a0\u00bb4306,3216,3220,3208,3214&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Nouvelle page web &#8211; Plantes indig\u00e8nes chez soi<\/h3>\n<p>Pour l\u2019occasion, nous lan\u00e7ons \u00e9galement une page web nomm\u00e9e \u00ab Les plantes indig\u00e8nes chez soi \u00bb, car ces m\u00eames abeilles ont aussi besoin du pollen des arbres et arbustes, dont certains fleurissent plus t\u00f4t que les pissenlits. Ils ont aussi besoin des fleurs sauvages indig\u00e8nes qui fleurissent \u00e0 plusieurs moments dans la saison.<\/p>\n<p>Visitez cette page web et apprenez comment encourager ces fleurs dans votre cour, sur votre terrain ou dans vos sous-bois. Vous profiterez de la visite de nombreuses esp\u00e8ces d\u2019insectes b\u00e9n\u00e9fiques, qui attireront aussi les oiseaux chez vous.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/fr\/plantes-chez-soi\/\u00a0\u00bb button_text=\u00a0\u00bbPage \u00abPlantes indig\u00e8nes chez soi\u00bb\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Qui sont les pollinisateurs?<\/h1>\n<p>Les pollinisateurs comprennent les abeilles, les papillons de jour et de nuit, les gu\u00eapes, les mouches, les col\u00e9opt\u00e8res, les fourmis, les colibris et les petits mammif\u00e8res qui se nourrissent du nectar et du pollen des fleurs. Dans d&rsquo;autres parties du monde, m\u00eame les chauves-souris assurent la pollinisation! En qu\u00eate de nourriture, les pollinisateurs se d\u00e9placent de plante en plante en transportant le pollen sur leur corps. Cela permet le transfert de mat\u00e9riel g\u00e9n\u00e9tique essentiel au syst\u00e8me de reproduction de la plupart des plantes \u00e0 fleurs.<\/p>\n<p>Pendant des millions d&rsquo;ann\u00e9es, les plantes et les pollinisateurs ont \u00e9volu\u00e9 ensemble dans cette r\u00e9gion, formant une relation mutuellement b\u00e9n\u00e9fique. Bien que d&rsquo;autres cr\u00e9atures soient \u00e9galement des pollinisateurs, ce sont les insectes comme les abeilles et les papillons qui sont les mieux adapt\u00e9s pour assurer la reproduction de la majorit\u00e9 des plantes indig\u00e8nes. En fait, il existe plus de 800 esp\u00e8ces d&rsquo;abeilles indig\u00e8nes au Canada, ce qui en fait de loin les principaux insectes pollinisateurs.<\/p>\n<p>Quant aux abeilles domestiques, elles ont \u00e9t\u00e9 import\u00e9es de d&rsquo;autres r\u00e9gions du monde. Bien que leur contribution soit importante pour le secteur agricole et la production de d&rsquo;autres produits comme le miel et la cire, nos abeilles indig\u00e8nes sont particuli\u00e8rement bien adapt\u00e9es \u00e0 la pollinisation des plantes indig\u00e8nes locales. Avec d&rsquo;autres pollinisateurs, les abeilles indig\u00e8nes assurent la sant\u00e9 de nos \u00e9cosyst\u00e8mes locaux, comme les marais qui fournissent des <a href=\"https:\/\/www.conservationcouncil.ca\/fr\/les-marecages-les-marais-les-tourbieres-les-estuaires-ainsi-que-les-marais-salants-sont-des-ecosystemes-vitaux-pour-la-survie-de-nos-communautes-2\/\" target=\"_blank\" rel=\"noopener\">services \u00e9cosyst\u00e9miques<\/a> tels que la gestion des eaux de pluie.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/04\/pollinators-and-flowers.jpg\u00a0\u00bb title_text=\u00a0\u00bbpollinators-and-flowers\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_divider _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Comment aider les pollinisateurs \u00e0 prosp\u00e9rer<\/h1>\n<p>Pour r\u00e9sumer, les pollinisateurs sont vitaux non seulement pour notre existence en tant qu&rsquo;\u00eatres humains, mais aussi pour notre plan\u00e8te. Pour maintenir la diversit\u00e9 de nos \u00e9cosyst\u00e8mes, notre r\u00e9gion a besoin de populations de pollinisateurs indig\u00e8nes en bonne sant\u00e9 pour assurer la production de la prochaine g\u00e9n\u00e9ration de plantes. Notre s\u00e9curit\u00e9 alimentaire en d\u00e9pend \u00e9galement.<\/p>\n<p>Pour accomplir leur cycle de vie et prosp\u00e9rer, les pollinisateurs ont besoin de nectar, de pollen et d&rsquo;abris que leur offre une grande vari\u00e9t\u00e9 de plantes. L&rsquo;objectif de cette campagne est de fournir des informations sur la mani\u00e8re dont nous pouvons tous participer aux efforts de conservation dont les pollinisateurs ont besoin. Travaillons ensemble pour aider ces cr\u00e9atures essentielles dans nos vies.<\/p>\n<ul>\n<li>Les abeilles, les papillons et les autres pollinisateurs d\u00e9pendent de la diversit\u00e9 des plantes, surtout des fleurs indig\u00e8nes qui poussent dans des environnements sans pesticides.<\/li>\n<li>Les pollinisateurs et les plantes indig\u00e8nes ont \u00e9volu\u00e9 ensemble pour s\u2019entraider. En ajoutant quelques plantes indig\u00e8nes dans vos plates-bandes, vous contribuez directement \u00e0 la cr\u00e9ation d\u2019habitats o\u00f9 ils peuvent se nourrir et se reproduire.<\/li>\n<li>Choisissez une vari\u00e9t\u00e9 de plantes qui fleurissent \u00e0 des p\u00e9riodes diff\u00e9rentes afin que les pollinisateurs disposent d\u2019une source de nourriture du printemps \u00e0 l\u2019automne.<\/li>\n<li>Plantez des <a href=\"https:\/\/ecovision2025.ca\/fr\/arbres-indigenes\/\" target=\"_blank\" rel=\"noopener\">arbres indig\u00e8nes<\/a> comme les \u00e9rables \u00e0 sucre et les ch\u00eanes rouges. Ils fleuriront au printemps et produiront du nectar pour les pollinisateurs tout en fournissant un habitat et de la nourriture aux oiseaux et autres animaux.<\/li>\n<li>Certains pollinisateurs font leur nid dans les plantes et le bois morts, ou s\u2019enfouissent dans le sol. Laissez des plantes et des feuilles mortes, des b\u00fbches de bois et de sol expos\u00e9 autour de votre jardin.<\/li>\n<li>Tondez l\u2019herbe moins souvent, peut-\u00eatre toutes les 2 ou 3 semaines. Le tr\u00e8fle, les pissenlits et d\u2019autres fleurs comme les violettes sont excellentes pour les pollinisateurs.<\/li>\n<li>Placez un plat d\u2019eau peu profond avec quelques pierres pour que les pollinisateurs puissent boire et ne pas tomber dedans. N\u2019oubliez pas de le remplir souvent d\u2019eau fra\u00eeche.<\/li>\n<li>Achetez ou construisez un nichoir \u00e0 abeilles et veillez \u00e0 l\u2019entretenir.<\/li>\n<li>Parlez-en \u00e0 vos amis et faites d\u00e9couvrir aux enfants ce que vous faites pour aider les pollinisateurs.<\/li>\n<li>Partagez des graines, des plantes et des conseils de jardinage avec vos voisins et vos coll\u00e8gues jardiniers.<\/li>\n<\/ul>\n<ul><\/ul>\n<p>[\/et_pb_text][et_pb_cta title=\u00a0\u00bbJardins des pollinisateurs\u00a0\u00bb button_text=\u00a0\u00bbClick Here\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb30px\u00a0\u00bb body_font_size=\u00a0\u00bb18px\u00a0\u00bb background_color=\u00a0\u00bb#75ad32&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][et_pb_text _builder_version=\u00a0\u00bb4.20.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Cette ann\u00e9e, dans le but de cr\u00e9er davantage d&rsquo;habitats pour les pollinisateurs dans la r\u00e9gion, des jardins de pollinisateurs avec quelques esp\u00e8ces indig\u00e8nes seront plant\u00e9s dans chacune des trois municipalit\u00e9s. Nous publierons des mises \u00e0 jour de ces jardins sur cette page.<\/p>\n<p>Nous invitons les citoyens de la r\u00e9gion \u00e0 r\u00e9server un espace dans leurs plates-bandes pour des fleurs indig\u00e8nes afin d&rsquo;aider les pollinisateurs, et \u00e0 nous contacter s&rsquo;ils ont besoin de plus d&rsquo;informations. L&rsquo;objectif est d&rsquo;en avoir le plus possible dans les ann\u00e9es \u00e0 venir afin de former des corridors permettant aux pollinisateurs de disposer d&rsquo;un abri et d&rsquo;une source de nourriture en abondance.<\/p>\n<p>Le <a href=\"https:\/\/www.especesenvahissantesnb.ca\/jardinez-intelligemment\" target=\"_blank\" rel=\"noopener\">programme <em>Jardinez Intelligemment <\/em><\/a>Plant Wise du Conseil sur les esp\u00e8ces envahissantes du Nouveau-Brunswick (CEENB) aide les jardiniers <span>et le secteur de l&rsquo;horticulture (ornementale) \u00e0 comprendre quelles sont les plantes envahissantes et nuisibles pour nos communaut\u00e9s. <\/span>Leur <a href=\"https:\/\/static1.squarespace.com\/static\/6262a840044e5f29d7483c93\/t\/64b5dfeb2ac8d15fb5d5fc07\/1689640945003\/NBISC-NSISC+Invasive+Species+Guide_2023_FR.pdf\" target=\"_blank\" rel=\"noopener\">guide de 60 pages<\/a> propose des alternatives de plantes indig\u00e8nes qui sont \u00e9galement b\u00e9n\u00e9fiques pour les pollinisateurs.<\/p>\n<p><span>Jardinez Intelligemment est un programme national qui aide les jardiniers et le secteur de l&rsquo;horticulture (ornementale) \u00e0 comprendre quelles sont les plantes envahissantes et nuisibles pour nos communaut\u00e9s et \u00e0 faire des choix judicieux.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2023\/04\/Ilots-Pollinisateurs-no-logos.jpg\u00a0\u00bb alt=\u00a0\u00bbHabitat-corridor-pollinators\u00a0\u00bb title_text=\u00a0\u00bbIlots-Pollinisateurs-no-logos\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/04\/Pollinator-gardens.jpg\u00a0\u00bb title_text=\u00a0\u00bbPollinator-gardens\u00a0\u00bb show_in_lightbox=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">Des jardins de pollinisateurs dans la communaut\u00e9<\/h3>\n<p style=\"text-align: center;\">En partenariat avec les groupes de bassins versants de la r\u00e9gion, les \u00e9coles, les municipalit\u00e9s et d\u2019autres organismes, des jardins collectifs pour pollinisateurs prennent forme dans la communaut\u00e9.<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00a0\u00bb3259,3255,3257,3237,3253,3261,3239,3241&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Certification Ville amie des monarques de la Fondation David Suzuki<\/h2>\n<p style=\"text-align: center;\">En 2023, les municipalit\u00e9s de Shediac et de Cap-Acadie ont re\u00e7u la certification <a href=\"https:\/\/fr.davidsuzuki.org\/passez-a-laction\/agissez-localement\/effet-papillon\/ville-amie-des-monarques\/\" target=\"_blank\" rel=\"noopener\">Ville amie des monarques de la Fondation David Suzuki<\/a> en partenariat avec Nature NB. Cette certification confirme l&rsquo;engagement des deux municipalit\u00e9s \u00e0 pr\u00e9server l&rsquo;habitat du monarque par des actions concr\u00e8tes telles que la distribution gratuite d&rsquo;ascl\u00e9piades, la collecte de semences, la cr\u00e9ation d&rsquo;un jardin de d\u00e9monstration et de plates-bandes propices au monarque, ainsi que l&rsquo;organisation de diverses activit\u00e9s citoyennes. En participant \u00e0 cette initiative, les municipalit\u00e9s prennent part \u00e0 un v\u00e9ritable effet papillon.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2023\/11\/Ami-Monarque-Shediac.jpg\u00a0\u00bb title_text=\u00a0\u00bbAmi Monarque Shediac\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb75%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2023\/11\/Ami-Monarque-Cap-Acadie-Fr.jpg\u00a0\u00bb title_text=\u00a0\u00bbAmi Monarque Cap-Acadie Fr\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_cta title=\u00a0\u00bbVid\u00e9os \u00e9ducatives sur les pollinisateurs\u00a0\u00bb button_text=\u00a0\u00bbClick Here\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb38px\u00a0\u00bb body_font_size=\u00a0\u00bb19px\u00a0\u00bb background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mCxrTlcpWqk?rel=0\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/QDI6c_2MN2U?rel=0\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_cta title=\u00a0\u00bbLiens int\u00e9ressants\u00a0\u00bb button_text=\u00a0\u00bbClick Here\u00a0\u00bb _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb38px\u00a0\u00bb body_font_size=\u00a0\u00bb19px\u00a0\u00bb background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Visitez ces sites web pour en savoir plus<\/p>\n<p>[\/et_pb_cta][et_pb_text _builder_version=\u00a0\u00bb4.20.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Conservation de la nature Canada vous invite \u00e0 laisser votre pelouse pousser en mai<br \/><\/strong><a href=\"https:\/\/www.natureconservancy.ca\/fr\/nous-trouver\/quebec\/communiques\/conservation-laisser-pelouse-pousser.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.natureconservancy.ca\/fr\/nous-trouver\/quebec\/communiques\/conservation-laisser-pelouse-pousser.html<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Pollinator Partnership Canada<br \/><\/strong><a href=\"https:\/\/pollinatorpartnership.ca\/fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pollinatorpartnership.ca\/fr\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Bee City Canada &#8211; En savoir plus sur les pollinisateurs (En anglais)<\/strong><br \/><a href=\"https:\/\/beecitycanada.org\/fr\/pollinator-resources\/learn-about-pollinators\/\" target=\"_blank\" rel=\"noopener\">https:\/\/beecitycanada.org\/fr\/pollinator-resources\/learn-about-pollinators\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; HELPING MONARCHS AND POLLINATORS: Rethinking Mowing (En anglais)<br \/><a href=\"https:\/\/cwf-fcf.org\/en\/explore\/monarchs\/Helping-Monarchs-and-Pollinators-Rethinking-Mowing.pdf\">https:\/\/cwf-fcf.org\/en\/explore\/monarchs\/Helping-Monarchs-and-Pollinators-Rethinking-Mowing.pdf<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Laisser pousser pour la p\u00e9rennit\u00e9!<\/strong><br \/><a href=\"https:\/\/cwf-fcf.org\/fr\/explorer\/pollinisateurs\/laisser-pousser-pour-la-prennit\/\" target=\"_blank\" rel=\"noopener\">https:\/\/cwf-fcf.org\/fr\/explorer\/pollinisateurs\/laisser-pousser-pour-la-prennit\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Des habitats fauniques chez nous &#8211; Comment tout le monde peut aider la faune du Canada<\/strong><br \/><a href=\"https:\/\/blog.cwf-fcf.org\/index.php\/fr\/des-habitats-fauniques-chez-nous-comment-tout-le-monde-peut-aider-la-faune-du-canada\/\" target=\"_blank\" rel=\"noopener\">https:\/\/blog.cwf-fcf.org\/index.php\/fr\/des-habitats-fauniques-chez-nous-comment-tout-le-monde-peut-aider-la-faune-du-canada\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Le r\u00e9tablissement des pollinisateurs<br \/><\/strong><a href=\"https:\/\/banwithaplan.org\/fr\/le-retablissement-des-pollinisateurs\/\" target=\"_blank\" rel=\"noopener\">https:\/\/banwithaplan.org\/fr\/le-retablissement-des-pollinisateurs\/<\/a><strong><br \/><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; L&rsquo;ABC de la Pollinisation<br \/><\/strong><a href=\"https:\/\/cwf-fcf.org\/fr\/ressources\/pour-enseignants\/lecons\/labc-de-la-pollinisation.html\" target=\"_blank\" rel=\"noopener\">https:\/\/cwf-fcf.org\/fr\/ressources\/pour-enseignants\/lecons\/labc-de-la-pollinisation.html<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Nous voulons inciter les pollinisateurs \u00e0 revenir dans nos arri\u00e8re-cours<\/strong><br \/><a href=\"https:\/\/www.youtube.com\/watch?v=yEBrScElkQA\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/watch?v=yEBrScElkQA<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Assurer la p\u00e9rennit\u00e9 des pollinisateurs<br \/><\/strong><a href=\"https:\/\/cwf-fcf.org\/fr\/explorer\/pollinisateurs\/\" target=\"_blank\" rel=\"noopener\">https:\/\/cwf-fcf.org\/fr\/explorer\/pollinisateurs\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Jardinage pour la faune<\/strong><br \/><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbXB2MWo4m-YuQ3SHg0w7sgkdFm3UMIn_\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/playlist?list=PLbXB2MWo4m-YuQ3SHg0w7sgkdFm3UMIn_<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Agriculture et agroalimentaire Canada &#8211; Les insectes pollinisateurs indig\u00e8nes et l\u2019agriculture au Canada<\/strong><br \/><a href=\"https:\/\/publications.gc.ca\/collections\/collection_2014\/aac-aafc\/A59-12-2014-fra.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/publications.gc.ca\/collections\/collection_2014\/aac-aafc\/A59-12-2014-fra.pdf<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Gouvernement du Canada &#8211; Am\u00e9nagez un jardin pour les pollinisateurs \u2013 D\u00e9fi de protection de la nature<\/strong><br \/><a href=\"https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/patrimoine-naturel\/activites\/amenagez-jardin-pollinisateurs.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.canada.ca\/fr\/environnement-changement-climatique\/services\/patrimoine-naturel\/activites\/amenagez-jardin-pollinisateurs.html<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Wildlife Preservation Canada &#8211; What is causing wild bee declines?<\/strong><br \/><a href=\"\/\/wildlifepreservation.ca\/blog\/what-is-causing-wild-bee-declines\/?utm_source=facebook&amp;utm_medium=organic-social&amp;utm_campaign=&amp;fbclid=IwAR29AGsqfEk8uxHcIHecbjHu3V9mbS2qfZP-3pxWnvsYmy3VbrfBXgYEync\" target=\"_blank\" rel=\"noopener\">https:\/\/wildlifepreservation.ca\/blog\/what-is-causing-wild-bee-declines\/?<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Parcs Canada &#8211; Faites pousser des plantes pour les pollinisateurs<br \/><\/strong><a href=\"https:\/\/www.pc.gc.ca\/fr\/nature\/science\/conservation\/plantes-pollinisateurs-plant-pollinators\" target=\"_blank\" rel=\"noopener\">https:\/\/www.pc.gc.ca\/fr\/nature\/science\/conservation\/plantes-pollinisateurs-plant-pollinators<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Radio Canada (audio) &#8211; En mai, oubliez la tondeuse et aidez les insectes pollinisateurs : Claude Drolet<\/strong><br \/><a href=\"https:\/\/ici.radio-canada.ca\/ohdio\/premiere\/emissions\/le-15-18\/segments\/entrevue\/354110\/tondeuse-gazon-mai-abeilles-pollinisateurs-fleurs-pissenlits\" target=\"_blank\" rel=\"noopener\">https:\/\/ici.radio-canada.ca\/ohdio\/premiere\/emissions\/le-15-18\/segments\/entrevue\/354110\/tondeuse-gazon-mai-abeilles-pollinisateurs-fleurs-pissenlits<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Bumble Bee Watch (en anglais)<\/strong><br \/><a href=\"https:\/\/www.bumblebeewatch.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.bumblebeewatch.org\/<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Monarchs and Milkweed in New Brunswick (en anglais)<br \/><\/strong><a href=\"https:\/\/www.inaturalist.org\/projects\/monarchs-and-milkweed-in-new-brunswick\" target=\"_blank\" rel=\"noopener\">https:\/\/www.inaturalist.org\/projects\/monarchs-and-milkweed-in-new-brunswick<\/a><\/p>\n<p style=\"text-align: center;\">Conseil sur les esp\u00e8ces envahissantes du Nouveau-Brunswick (CEENB) &#8211; Programme Jardinez Intelligemment<br \/><a href=\"https:\/\/www.especesenvahissantesnb.ca\/jardinez-intelligemment\" target=\"_blank\" rel=\"noopener\">https:\/\/www.especesenvahissantesnb.ca\/jardinez-intelligemment\u00a0<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Besides No Mow May, add native plants for pollinators, conservationists say (en anglais)<br \/><\/strong><a href=\"https:\/\/www.saltwire.com\/halifax\/news\/besides-no-mow-may-add-native-plants-for-pollinators-conservationists-say-100730807\/?fbclid=IwAR2iFQ1nkXU00txa41ZPzn1PjpZQRzXbOfBtewIRLNhtuT5wZAFoRpfr7Hg\" target=\"_blank\" rel=\"noopener\">https:\/\/www.saltwire.com\/halifax\/news\/besides-no-mow-may-add-native-plants-for-pollinators-conservationists-say-100730807\/?fbclid=IwAR2iFQ1nkXU00txa41ZPzn1PjpZQRzXbOfBtewIRLNhtuT5wZAFoRpfr7Hg<\/a><\/p>\n<p style=\"text-align: center;\"><strong>CBC News &#8211; Native plants finding their way to more Nova Scotia gardens this spring (en anglais)<\/strong><br \/><a href=\"https:\/\/www.cbc.ca\/news\/canada\/nova-scotia\/native-plants-nova-scotia-1.6420201\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cbc.ca\/news\/canada\/nova-scotia\/native-plants-nova-scotia-1.6420201<\/a><\/p>\n<p style=\"text-align: center;\"><strong>CBC News &#8211; No Mow May is fine, but conservationists say more can be done to help pollinators (en anglais)<br \/><\/strong><a href=\"https:\/\/www.cbc.ca\/news\/canada\/nova-scotia\/no-mow-may-biodiversity-native-plant-species-pollinators-1.6456549?fbclid=IwAR0A21mAxVzmc8Z7IObeoEnKKFohQjds-cNDNFSzmWnn1BBx-wgQuuzev9c\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cbc.ca\/news\/canada\/nova-scotia\/no-mow-may-biodiversity-native-plant-species-pollinators-1.6456549?fbclid=IwAR0A21mAxVzmc8Z7IObeoEnKKFohQjds-cNDNFSzmWnn1BBx-wgQuuzev9c<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Groupe de d\u00e9veloppement durable du Pays de Cocagne &#8211; Pollinisateurs sauvages &amp; leurs habitats naturels<\/strong><br \/><a href=\"https:\/\/ecopaysdecocagne.ca\/fr\/nature\/pollinisateurs\" target=\"_blank\" rel=\"noopener\">https:\/\/ecopaysdecocagne.ca\/fr\/nature\/pollinisateurs<\/a><\/p>\n<p style=\"text-align: center;\"><span><strong>iNaturalist &#8211; Pollinisateurs dans la r\u00e9gion de Cocagne<\/strong><br \/><a href=\"https:\/\/inaturalist.ca\/observations?place_id=any&amp;project_id=pollinisateurs-de-cocagne-nb-pollinators&amp;verifiable=any\" target=\"_blank\" rel=\"noopener\">https:\/\/inaturalist.ca\/observations?place_id=any&amp;project_id=pollinisateurs-de-cocagne-nb-pollinators&amp;verifiable=any<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>Les ami.e.s de la nature du sud-est du NB<\/strong><br \/><a href=\"https:\/\/photos.google.com\/share\/AF1QipN1_OUx3DBU0WyH4mMmXjmtjE6ChIJPXA3f9aIZXXPtjAWmFRFY_QI5NmueB-MGYQ?key=TGJKdjFwV3puVU9jbEI2SkM0S1BmUkdvWUtaS3RB\" target=\"_blank\" rel=\"noopener\">Les pollinisateurs du sud-est du NB, par Stuart Tingley<\/a><br \/><\/span><\/p>\n<p style=\"text-align: center;\"><span><\/span><\/p>\n<h2 style=\"text-align: center;\"><span>Outils et activit\u00e9s \u00e9ducationnelles<\/span><\/h2>\n<p style=\"text-align: center;\"><span><strong>D\u00e9pliant d&rsquo;une page (avec code QR menant \u00e0 cette page) disponible pour t\u00e9l\u00e9charger et imprimer\u00a0 &#8211; Bilingue fr-ang, 7.5&#215;11 po.<br \/><\/strong><a href=\"https:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/06\/Depliant-pollinisateurs-Fr-Eng-3.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/06\/Depliant-pollinisateurs-Fr-Eng-3.pdf<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>Affiche sur les pollinisateurs (avec un code QR menant \u00e0 cette page) disponible pour t\u00e9l\u00e9charger et imprimer &#8211; Bilingue fr-ang, 11&#215;17 po.<br \/><\/strong><\/span><a href=\"https:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/06\/Affiche-Pollinisateurs-Poster-11x17-3.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ecovision2025.ca\/wp-content\/uploads\/2022\/06\/Affiche-Pollinisateurs-Poster-11&#215;17-3.pdf<\/a><\/p>\n<p style=\"text-align: center;\"><span><strong>F\u00e9d\u00e9ration canadienne de la faune &#8211; Espaces de vie, un programme de conservation des pollinisateurs<\/strong><br \/><strong>\u00e0 l\u2019intention des \u00e9coles<br \/><\/strong><a href=\"https:\/\/cwf-fcf.org\/fr\/explorer\/espaces-de-vie\/#plus\" target=\"_blank\" rel=\"noopener\">https:\/\/cwf-fcf.org\/fr\/explorer\/espaces-de-vie\/#plus<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>Canadian Wildlife Federation &#8211; Educational Activities for Schools (en anglais)<\/strong><br \/><a href=\"https:\/\/education.cwf-fcf.org\/library\/resources\/get\/230909\/Educator%20Guide%20-%20Pollinators.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/education.cwf-fcf.org\/library\/resources\/get\/230909\/Educator%20Guide%20-%20Pollinators.pdf<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>Pollinator Partnership &#8211; Educational Activities for Schools (en anglais)<\/strong><br \/><a href=\"https:\/\/pollinatorpartnership.ca\/en\/p2c-kids\" target=\"_blank\" rel=\"noopener\">https:\/\/pollinatorpartnership.ca\/en\/p2c-kids<\/a><br \/><\/span><span><\/span><\/p>\n<p style=\"text-align: center;\"><span><strong>Pollinator Partnership &#8211; Bee Smart School Garden Kit (en anglais)<br \/><\/strong><\/span><a href=\"https:\/\/www.pollinator.org\/bee-smart\" target=\"_blank\" rel=\"noopener\">https:\/\/www.pollinator.org\/bee-smart<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb34px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2018\/02\/EV2025_Logo.png\u00a0\u00bb alt=\u00a0\u00bbEco Vision 2025&Prime; title_text=\u00a0\u00bbEco Vision 2025&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb32%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.16.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span>Cette initiative est parrain\u00e9e par :<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2024\/10\/Capacadie_Logo_Full_Color_Rgb_900px_w_72ppi.jpg\u00a0\u00bb title_text=\u00a0\u00bbCapacadie_Logo_Full_Color_Rgb_900px_w_72ppi\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/capacadie.ca\/fr\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb54%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb-27px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ecovision2025.ca\/wp-content\/uploads\/2024\/10\/ShediacLogo.jpg\u00a0\u00bb title_text=\u00a0\u00bbPrint\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/shediac.ca\/en\/\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb54%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les pollinisateurs comme les abeilles et les papillons sont essentiels \u00e0 notre environnement et \u00e0 notre \u00e9conomie. Ils jouent un r\u00f4le important dans la croissance des arbres, des fleurs et des autres plantes partout dans le monde. En fait, pr\u00e8s de 85 % de toutes les plantes \u00e0 fleurs en d\u00e9pendent pour produire des fruits [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2935,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2938","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/pages\/2938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/comments?post=2938"}],"version-history":[{"count":5,"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/pages\/2938\/revisions"}],"predecessor-version":[{"id":4625,"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/pages\/2938\/revisions\/4625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/media\/2935"}],"wp:attachment":[{"href":"https:\/\/ecovision2025.ca\/fr\/wp-json\/wp\/v2\/media?parent=2938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}